{"id":1560,"count":1,"description":"","link":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/","name":"Ideas Defence Day Sale","slug":"ideas-defence-day-sale","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ideas Defence Day Sale Archives - Good Times Blogs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ideas Defence Day Sale Archives - Good Times Blogs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"Good Times Blogs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/tag\\\/ideas-defence-day-sale\\\/\",\"url\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/tag\\\/ideas-defence-day-sale\\\/\",\"name\":\"Ideas Defence Day Sale Archives - Good Times Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/tag\\\/ideas-defence-day-sale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/tag\\\/ideas-defence-day-sale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ideas Defence Day Sale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#website\",\"url\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/\",\"name\":\"Good Times Blogs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#organization\",\"name\":\"Good Times Blogs\",\"url\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/GT-Good-Times-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/GT-Good-Times-Logo.png\",\"width\":206,\"height\":183,\"caption\":\"Good Times Blogs\"},\"image\":{\"@id\":\"https:\\\/\\\/www.goodtimes.com.pk\\\/blogs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/goodtimes.GT\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ideas Defence Day Sale Archives - Good Times Blogs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/","og_locale":"en_US","og_type":"article","og_title":"Ideas Defence Day Sale Archives - Good Times Blogs","og_url":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/","og_site_name":"Good Times Blogs","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/","url":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/","name":"Ideas Defence Day Sale Archives - Good Times Blogs","isPartOf":{"@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#website"},"breadcrumb":{"@id":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.goodtimes.com.pk\/blogs\/tag\/ideas-defence-day-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.goodtimes.com.pk\/blogs\/"},{"@type":"ListItem","position":2,"name":"Ideas Defence Day Sale"}]},{"@type":"WebSite","@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#website","url":"https:\/\/www.goodtimes.com.pk\/blogs\/","name":"Good Times Blogs","description":"","publisher":{"@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goodtimes.com.pk\/blogs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#organization","name":"Good Times Blogs","url":"https:\/\/www.goodtimes.com.pk\/blogs\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#\/schema\/logo\/image\/","url":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-content\/uploads\/2023\/10\/GT-Good-Times-Logo.png","contentUrl":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-content\/uploads\/2023\/10\/GT-Good-Times-Logo.png","width":206,"height":183,"caption":"Good Times Blogs"},"image":{"@id":"https:\/\/www.goodtimes.com.pk\/blogs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/goodtimes.GT"]}]}},"_links":{"self":[{"href":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-json\/wp\/v2\/tags\/1560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.goodtimes.com.pk\/blogs\/wp-json\/wp\/v2\/posts?tags=1560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}